{"id":1511,"date":"2012-03-11T04:03:00","date_gmt":"2012-03-11T04:03:00","guid":{"rendered":"http:\/\/elpobrecitohablador.es\/wordpress\/2012\/03\/11\/twitters-de-la-semana-2012-03-11-2\/"},"modified":"2012-03-11T04:03:00","modified_gmt":"2012-03-11T04:03:00","slug":"twitters-de-la-semana-2012-03-11-2","status":"publish","type":"post","link":"https:\/\/elpobrecitohablador.es\/wordpress\/2012\/03\/11\/twitters-de-la-semana-2012-03-11-2\/","title":{"rendered":"Twitters de la Semana 2012-03-11"},"content":{"rendered":"<ul class=\"aktt_tweet_digest\">\n<li>RT @<a href=\"http:\/\/twitter.com\/zapirika\" class=\"aktt_username\">zapirika<\/a> &quot;He apoyado la petici\u00f3n Pide al Ministro de Exteriores que ayude a proteger a la poblaci\u00f3n civil siria YA! &quot;CLARO COMO EN LIBIA <a href=\"http:\/\/twitter.com\/zapirika\/statuses\/176740948934537217\" class=\"aktt_tweet_reply\">in reply to zapirika<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/176741882813091840\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>Puaaggg vomitivos #<a href=\"http:\/\/search.twitter.com\/search?q=%23VizasPrats\" class=\"aktt_hashtag\">VizasPrats<\/a> risitas con los #<a href=\"http:\/\/search.twitter.com\/search?q=%23Borbones\" class=\"aktt_hashtag\">Borbones<\/a> #S\u00e1licos y el #<a href=\"http:\/\/search.twitter.com\/search?q=%23Pr\" class=\"aktt_hashtag\">Pr<\/a> ?ncipeCigarr\u00f3n #<a href=\"http:\/\/search.twitter.com\/search?q=%23Abanderado\" class=\"aktt_hashtag\">Abanderado<\/a>  saqueo del pueblo y  p\u00e9rdida d derechos <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/176997375401930754\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>#<a href=\"http:\/\/search.twitter.com\/search?q=%23AcademiaTV\" class=\"aktt_hashtag\">AcademiaTV<\/a> refugio par\u00e1sitos vividores cuento y mentira,autoalab\u00e1ndose,babeando ante el poder, #<a href=\"http:\/\/search.twitter.com\/search?q=%23Presentadoras\" class=\"aktt_hashtag\">Presentadoras<\/a> b\u00fascando #<a href=\"http:\/\/search.twitter.com\/search?q=%23Pr\" class=\"aktt_hashtag\">Pr<\/a> ?ncipesCigarrones <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/176998832943546368\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>Verguenza @<a href=\"http:\/\/twitter.com\/rtve\" class=\"aktt_username\">rtve<\/a> y resto  #<a href=\"http:\/\/search.twitter.com\/search?q=%23papanatas\" class=\"aktt_hashtag\">papanatas<\/a> genuflexos ante #<a href=\"http:\/\/search.twitter.com\/search?q=%23S\" class=\"aktt_hashtag\">S<\/a> ?licas instituciones + desprestigiadas q el tonto q puede ser #<a href=\"http:\/\/search.twitter.com\/search?q=%23Rey\" class=\"aktt_hashtag\">Rey<\/a> y a\u00fan no lo tiramos <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177001200733011968\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/Twitchevique\" class=\"aktt_username\">Twitchevique<\/a> @cachu @<a href=\"http:\/\/twitter.com\/Laguantanamera\" class=\"aktt_username\">Laguantanamera<\/a> @vgutierrezf @<a href=\"http:\/\/twitter.com\/dpiloncita\" class=\"aktt_username\">dpiloncita<\/a> jaquear\u00eda constituci\u00f3n #<a href=\"http:\/\/search.twitter.com\/search?q=%23MonarcoBober\" class=\"aktt_hashtag\">MonarcoBober<\/a> ?a d &quot;disputados&quot;  #<a href=\"http:\/\/search.twitter.com\/search?q=%23sueldazos\" class=\"aktt_hashtag\">sueldazos<\/a> x completo <a href=\"http:\/\/twitter.com\/Twitchevique\/statuses\/177207874538323968\" class=\"aktt_tweet_reply\">in reply to Twitchevique<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177347532337315841\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>RT @<a href=\"http:\/\/twitter.com\/garanet\" class=\"aktt_username\">garanet<\/a>  &quot;Supremo revisa condena a Tasio Erkizia x participar en homenaje a &quot;Argala&quot; <a href=\"http:\/\/t.co\/04JQiRiq\" rel=\"nofollow\">http:\/\/t.co\/04JQiRiq<\/a> &quot; Tendr\u00e1n q reparar alg\u00fan d\u00eda <a href=\"http:\/\/twitter.com\/garanet\/statuses\/177353705891442688\" class=\"aktt_tweet_reply\">in reply to garanet<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177355456371625984\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>#<a href=\"http:\/\/search.twitter.com\/search?q=%23Jart\" class=\"aktt_hashtag\">Jart<\/a> ? x el #<a href=\"http:\/\/search.twitter.com\/search?q=%23SMI\" class=\"aktt_hashtag\">SMI<\/a> para cargos p\u00fablicos,al memos conseguir\u00edamos q lo subiesen aunque solo fuese x inter\u00e9s personal,es lo \u00fanico q funciona bien <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177357383956307968\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>Televisi\u00f3n Arabe emite im\u00e1genes falsas Siria:<a href=\"http:\/\/t.co\/AjC8pvuJ\" rel=\"nofollow\">http:\/\/t.co\/AjC8pvuJ<\/a> el resto alimenta manipulaci\u00f3n dando pavulo a bloguerxs tipo @<a href=\"http:\/\/twitter.com\/yoanisanchez\" class=\"aktt_username\">yoanisanchez<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177374847935066112\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/An0n_Dom\" class=\"aktt_username\">An0n_Dom<\/a> Puedes contar con nosotrxs desde #<a href=\"http:\/\/search.twitter.com\/search?q=%23Canarias\" class=\"aktt_hashtag\">Canarias<\/a> <a href=\"http:\/\/twitter.com\/An0n_Dom\/statuses\/177399158217515011\" class=\"aktt_tweet_reply\">in reply to An0n_Dom<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177400256126914560\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/rtve\" class=\"aktt_username\">rtve<\/a> babeando ante  #<a href=\"http:\/\/search.twitter.com\/search?q=%23promusicae\" class=\"aktt_hashtag\">promusicae<\/a> y #<a href=\"http:\/\/search.twitter.com\/search?q=%23Sgae\" class=\"aktt_hashtag\">Sgae<\/a> q de momento no denuncia, mienten + q hablan, las 1\u00aa 25 webs denunciadas <a href=\"http:\/\/t.co\/NKHybwfh\" rel=\"nofollow\">http:\/\/t.co\/NKHybwfh<\/a> y250? <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177405736115109891\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/victorfabalos\" class=\"aktt_username\">victorfabalos<\/a> Discrepo en lo d Lumpen,estos han luchado + q reclamados comunistas, #<a href=\"http:\/\/search.twitter.com\/search?q=%23ElLute\" class=\"aktt_hashtag\">ElLute<\/a> es @<a href=\"http:\/\/twitter.com\/libertadmontes\" class=\"aktt_username\">libertadmontes<\/a> y muchos an\u00f3nimos q se pudren <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177422638975688705\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/victorfabalos\" class=\"aktt_username\">victorfabalos<\/a> Creo recordar q #<a href=\"http:\/\/search.twitter.com\/search?q=%23Lenin\" class=\"aktt_hashtag\">Lenin<\/a> apoy\u00f3 una manifestaci\u00f3n convocada por los #<a href=\"http:\/\/search.twitter.com\/search?q=%23popes\" class=\"aktt_hashtag\">popes<\/a> rusos y con los + empobrecidos y alienados dl pueblo <a href=\"http:\/\/twitter.com\/victorfabalos\/statuses\/177423105000615937\" class=\"aktt_tweet_reply\">in reply to victorfabalos<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177435404994215938\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/LosPajarosPican\" class=\"aktt_username\">LosPajarosPican<\/a> &quot;Presidente Asociaci\u00f3n Prensa dimite tras amenazar con correazo a activista: <a href=\"http:\/\/t.co\/iAmaNMOG&quot;#violenciaestructural\" rel=\"nofollow\">http:\/\/t.co\/iAmaNMOG&quot;#violenciaestructural<\/a> no? <a href=\"http:\/\/twitter.com\/LosPajarosPican\/statuses\/177435852568399872\" class=\"aktt_tweet_reply\">in reply to LosPajarosPican<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177436902356557824\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>#<a href=\"http:\/\/search.twitter.com\/search?q=%23FF\" class=\"aktt_hashtag\">FF<\/a> Revuelta @<a href=\"http:\/\/twitter.com\/PEPE_TAVO24\" class=\"aktt_username\">PEPE_TAVO24<\/a> Graciasxcompartir @<a href=\"http:\/\/twitter.com\/pregkontprosgiz\" class=\"aktt_username\">pregkontprosgiz<\/a> @araxuwumy @<a href=\"http:\/\/twitter.com\/ugegeqax\" class=\"aktt_username\">ugegeqax<\/a> @slamazimk @<a href=\"http:\/\/twitter.com\/kelyseryz\" class=\"aktt_username\">kelyseryz<\/a> @juulianmatias @<a href=\"http:\/\/twitter.com\/DSJ_FFABIO\" class=\"aktt_username\">DSJ_FFABIO<\/a> @KankoGBL <a href=\"http:\/\/twitter.com\/PEPE_TAVO24\/statuses\/177429435010658305\" class=\"aktt_tweet_reply\">in reply to PEPE_TAVO24<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177438787067060225\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/victorfabalos\" class=\"aktt_username\">victorfabalos<\/a> Estamos de acuerdo, pero eso hoy es muy extensible a bastantes proletarios desclasados y traidores a su clase x alienaci\u00f3n <a href=\"http:\/\/twitter.com\/victorfabalos\/statuses\/177443622575288320\" class=\"aktt_tweet_reply\">in reply to victorfabalos<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177470823945338881\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/Karol_en_Red\" class=\"aktt_username\">Karol_en_Red<\/a> @rosa_in_mundo #<a href=\"http:\/\/search.twitter.com\/search?q=%23Frutos\" class=\"aktt_hashtag\">Frutos<\/a> no creo que de muchos, sin poner el enlace al art\u00edculo q se crit\u00edca y comentarios con aprobaci\u00f3n previa <a href=\"http:\/\/twitter.com\/Karol_en_Red\/statuses\/177474204004913152\" class=\"aktt_tweet_reply\">in reply to Karol_en_Red<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177477773454086145\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/Karol_en_Red\" class=\"aktt_username\">Karol_en_Red<\/a> @rosa_in_mundo El blog tiene los comentarios con aprobaci\u00f3n previa y no se cita el enlace al articulo d Alba Rico q se crit\u00edca <a href=\"http:\/\/twitter.com\/Karol_en_Red\/statuses\/177523947372425216\" class=\"aktt_tweet_reply\">in reply to Karol_en_Red<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177527220569509888\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/Karol_en_Red\" class=\"aktt_username\">Karol_en_Red<\/a> Con 0 comentarios desde 19\/02 y no publicando el q les mande no creo q esten x la labor d enterarse  que existen discrepancias <a href=\"http:\/\/twitter.com\/Karol_en_Red\/statuses\/177528194574983168\" class=\"aktt_tweet_reply\">in reply to Karol_en_Red<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/177531170022633473\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<li>@<a href=\"http:\/\/twitter.com\/EnriqueBeth\" class=\"aktt_username\">EnriqueBeth<\/a> #<a href=\"http:\/\/search.twitter.com\/search?q=%23RankingCaraduras\" class=\"aktt_hashtag\">RankingCaraduras<\/a> comenzando @<a href=\"http:\/\/twitter.com\/Jdominguezb\" class=\"aktt_username\">Jdominguezb<\/a> onde andara el #<a href=\"http:\/\/search.twitter.com\/search?q=%23Referendum\" class=\"aktt_hashtag\">Referendum<\/a>  o era q se sentara Rivero con @<a href=\"http:\/\/twitter.com\/jmsoria\" class=\"aktt_username\">jmsoria<\/a> a juga subastao? <a href=\"http:\/\/twitter.com\/EnriqueBeth\/statuses\/178260359797424130\" class=\"aktt_tweet_reply\">in reply to EnriqueBeth<\/a> <a href=\"http:\/\/twitter.com\/falsimedia\/statuses\/178266871034937344\" class=\"aktt_tweet_time\">#<\/a><\/li>\n<\/ul>\n<p class=\"aktt_credit\">Powered by <a href=\"http:\/\/alexking.org\/projects\/wordpress\">Twitter Tools<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RT @zapirika &quot;He apoyado la petici\u00f3n Pide al Ministro de Exteriores que ayude a proteger a la poblaci\u00f3n civil siria YA! &quot;CLARO COMO EN LIBIA in reply to zapirika # Puaaggg vomitivos #VizasPrats risitas con los #Borbones #S\u00e1licos y el #Pr ?ncipeCigarr\u00f3n #Abanderado saqueo del pueblo y p\u00e9rdida d derechos # #AcademiaTV refugio par\u00e1sitos vividores [&hellip;]<\/p>\n","protected":false},"author":290,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[369],"tags":[525],"class_list":["post-1511","post","type-post","status-publish","format-standard","hentry","category-sopa","tag-sopa"],"_links":{"self":[{"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/posts\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/users\/290"}],"replies":[{"embeddable":true,"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":0,"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/posts\/1511\/revisions"}],"wp:attachment":[{"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/categories?post=1511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elpobrecitohablador.es\/wordpress\/wp-json\/wp\/v2\/tags?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}